{"id":8506,"date":"2019-11-28T10:17:10","date_gmt":"2019-11-28T09:17:10","guid":{"rendered":"https:\/\/fundacioncomillas.es\/?p=8506"},"modified":"2023-12-04T11:59:34","modified_gmt":"2023-12-04T10:59:34","slug":"las-lenguas-en-espana-y-sus-dialectos","status":"publish","type":"post","link":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/","title":{"rendered":"Las lenguas en Espa\u00f1a y sus dialectos"},"content":{"rendered":"<p style=\"text-align: justify;\">La intenci\u00f3n de la redacci\u00f3n de este art\u00edculo es aclarar la confusi\u00f3n que algunos alumnos, sobre todo de pa\u00edses extranjeros, en referencia a \u00a0cu\u00e1les son las lenguas oficiales y cu\u00e1les los diferentes dialectos que encontramos dentro de nuestro pa\u00eds. No obstante, tambi\u00e9n entre espa\u00f1oles es una tem\u00e1tica que genera ciertas dudas.<\/p>\n<p style=\"text-align: justify;\">En primer lugar debemos definir cada una de estas palabras seg\u00fan la acepci\u00f3n del diccionario de la Real Academia Espa\u00f1ola:<\/p>\n<p style=\"text-align: justify;\"><strong>Lengua<\/strong>\u00a0es el \u201csistema de comunicaci\u00f3n verbal propio de una comunidad humana y que cuenta generalmente con escritura\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Dialecto<\/strong>\u00a0se define como la \u201cvariedad de un idioma que no alcanza la categor\u00eda social de lengua\u201d.<\/p>\n<h2>ESPA\u00d1A Y SUS DIALECTOS<\/h2>\n<p style=\"text-align: justify;\">Nuestro pa\u00eds es pluriling\u00fce donde<strong>\u00a0el espa\u00f1ol es la lengua oficial del estado<\/strong>. Las otras tres lenguas existentes en nuestro pa\u00eds y por lo tanto cooficiales son:<\/p>\n<p>&#8211;\u00a0<strong>El catal\u00e1n<\/strong>. Es la lengua oficial en Catalu\u00f1a, Valencia e Islas Baleares. Sin embargo tambi\u00e9n es lengua nativa fuera de nuestras fronteras, como es el caso del Principado de Andorra, en el puerto de Alghero (Cerde\u00f1a) y en casi toda la totalidad del d\u00e9partement de los Pirineos Orientales franceses. Lo hablan aproximadamente 8 millones de personas.<\/p>\n<p>&#8211;\u00a0<strong>El gallego<\/strong>. Hablado por unos 3 millones de personas en Galicia y en ciertas zonas lim\u00edtrofes de Le\u00f3n y Zamora.<\/p>\n<p>&#8211;\u00a0<strong>El vasco o euskera<\/strong>. No pertenece a la familia de lenguas rom\u00e1nicas como las dos anteriores. Se habla en el Pa\u00eds Vasco, Navarra y en algunas comarcas del sur de Francia. Si bien el origen de esta lengua no est\u00e1 del todo claro, los primeros textos que se conservan datan del siglo XVI. Se calcula que lo hablan unas 850.000 personas.<\/p>\n<h3>SEG\u00daN LA ZONA GEOGR\u00c1FICA<\/h3>\n<p style=\"text-align: justify;\">Para poder\u00a0<strong>diferenciar los dialectos<\/strong>\u00a0habidos en nuestro territorio y entenderlo de forma m\u00e1s precisa es necesario dividir el mapa en dos mitades: norte y sur; o\u00a0<strong>septentrional y meridional<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>En la parte norte o septentrional\u00a0<\/strong>encontramos predomina el\u00a0<strong>dominio de la \u201cs\u201d\u00a0<\/strong>al final de cada s\u00edlaba que la contiene. Frente a la\u00a0<strong>parte sur o meridional<\/strong>\u00a0donde el uso de esa \u201cs\u201d se convierte en una<strong>\u00a0\u201ch\u201d aspirada<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Por lo tanto, atendiendo a esta diferenciaci\u00f3n encontramos en la parte sur de la pen\u00ednsula: el Extreme\u00f1o, el Manchego, el Murciano, el Andaluz y el Canario. Mientras que en la parte norte se conservan hasta nuestros d\u00edas dialectos que desarrollaron simult\u00e1neamente al castellano como lenguas pero fueron absorbidas por \u00e9ste durante la Edad Media: el asturleon\u00e9s y el navarroaragon\u00e9s, dando lugar a los actuales bable y fablas aragonesas respectivamente.<\/p>\n<p style=\"text-align: justify;\">Estas lenguas y dialectos que conviven en nuestro pa\u00eds aportan indudablemente una gran diversidad cultural y ling\u00fc\u00edstica.<\/p>\n<p style=\"text-align: justify;\">Desde el\u00a0<a href=\"https:\/\/fundacioncomillas.es\/ciese-centro-universitario\/\">Centro Universitario CIESE-Fundaci\u00f3n Comillas<\/a>\u00a0os animamos a profundizar a\u00fan m\u00e1s en cada una de estas lenguas y dialectos para enriquecer vuestro conocimiento y vocabulario.<\/p>\n<p>Fuentes:<\/p>\n<p><a href=\"http:\/\/www.proel.org\/index.php?pagina=mundo\/indoeuro\/italico\/romance\/iberorromance\/catalan\" target=\"_blank\" rel=\"noopener\">http:\/\/www.proel.org\/index.php?pagina=mundo\/indoeuro\/italico\/romance\/iberorromance\/catalan<\/a><\/p>\n<p><a href=\"https:\/\/www.etxepare.eus\/es\/euskera\" target=\"_blank\" rel=\"noopener\">https:\/\/www.etxepare.eus\/es\/euskera<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La intenci\u00f3n de la redacci\u00f3n de este art\u00edculo es aclarar la confusi\u00f3n que algunos alumnos, sobre todo de pa\u00edses extranjeros, en referencia a \u00a0cu\u00e1les son las lenguas oficiales y cu\u00e1les los diferentes dialectos que encontramos dentro de nuestro pa\u00eds.<\/p>\n","protected":false},"author":3,"featured_media":8507,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[40,149],"tags":[309,308,201],"class_list":["post-8506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-curiosidades","tag-curiosidades","tag-dialectos","tag-espanol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las lenguas en Espa\u00f1a y sus dialectos - Fundaci\u00f3n Comillas<\/title>\n<meta name=\"description\" content=\"\u00bfCu\u00e1les son las lenguas oficiales y cu\u00e1les los diferentes dialectos que encontramos dentro de Espa\u00f1a? Te lo aclaramos...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las lenguas en Espa\u00f1a y sus dialectos - Fundaci\u00f3n Comillas\" \/>\n<meta property=\"og:description\" content=\"\u00bfCu\u00e1les son las lenguas oficiales y cu\u00e1les los diferentes dialectos que encontramos dentro de Espa\u00f1a? Te lo aclaramos...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Comillas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ciese.comillas\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-28T09:17:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-04T10:59:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fundacioncomillas.es\/wp-content\/uploads\/2023\/06\/las-lenguas-en-espana-y-sus-dialectos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"599\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fundacion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CIESEComillas\" \/>\n<meta name=\"twitter:site\" content=\"@CIESEComillas\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"fundacion\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/2019\\\/11\\\/28\\\/las-lenguas-en-espana-y-sus-dialectos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/2019\\\/11\\\/28\\\/las-lenguas-en-espana-y-sus-dialectos\\\/\"},\"author\":{\"name\":\"fundacion\",\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/#\\\/schema\\\/person\\\/3cdde58ad1a78de54c94309e39ec81cb\"},\"headline\":\"Las lenguas en Espa\u00f1a y sus dialectos\",\"datePublished\":\"2019-11-28T09:17:10+00:00\",\"dateModified\":\"2023-12-04T10:59:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/2019\\\/11\\\/28\\\/las-lenguas-en-espana-y-sus-dialectos\\\/\"},\"wordCount\":535,\"publisher\":{\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/2019\\\/11\\\/28\\\/las-lenguas-en-espana-y-sus-dialectos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fundacioncomillas.es\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/las-lenguas-en-espana-y-sus-dialectos.jpg\",\"keywords\":[\"curiosidades\",\"dialectos\",\"Espa\u00f1ol\"],\"articleSection\":[\"CULTURA\",\"Curiosidades\"],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/2019\\\/11\\\/28\\\/las-lenguas-en-espana-y-sus-dialectos\\\/\",\"url\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/2019\\\/11\\\/28\\\/las-lenguas-en-espana-y-sus-dialectos\\\/\",\"name\":\"Las lenguas en Espa\u00f1a y sus dialectos - Fundaci\u00f3n Comillas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/2019\\\/11\\\/28\\\/las-lenguas-en-espana-y-sus-dialectos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/2019\\\/11\\\/28\\\/las-lenguas-en-espana-y-sus-dialectos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fundacioncomillas.es\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/las-lenguas-en-espana-y-sus-dialectos.jpg\",\"datePublished\":\"2019-11-28T09:17:10+00:00\",\"dateModified\":\"2023-12-04T10:59:34+00:00\",\"description\":\"\u00bfCu\u00e1les son las lenguas oficiales y cu\u00e1les los diferentes dialectos que encontramos dentro de Espa\u00f1a? Te lo aclaramos...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/2019\\\/11\\\/28\\\/las-lenguas-en-espana-y-sus-dialectos\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/2019\\\/11\\\/28\\\/las-lenguas-en-espana-y-sus-dialectos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/2019\\\/11\\\/28\\\/las-lenguas-en-espana-y-sus-dialectos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fundacioncomillas.es\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/las-lenguas-en-espana-y-sus-dialectos.jpg\",\"contentUrl\":\"https:\\\/\\\/fundacioncomillas.es\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/las-lenguas-en-espana-y-sus-dialectos.jpg\",\"width\":599,\"height\":400,\"caption\":\"Las lenguas en Espa\u00f1a y sus dialectos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/2019\\\/11\\\/28\\\/las-lenguas-en-espana-y-sus-dialectos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las lenguas en Espa\u00f1a y sus dialectos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/\",\"name\":\"Fundaci\u00f3n Comillas\",\"description\":\"La Fundaci\u00f3n Comillas del Espa\u00f1ol y la Cultura Hisp\u00e1nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/#organization\",\"name\":\"Fundaci\u00f3n Comillas\",\"alternateName\":\"Fundaci\u00f3n Comillas - CIESE\",\"url\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fundacioncomillas.es\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-fundacion-comillas-.png\",\"contentUrl\":\"https:\\\/\\\/fundacioncomillas.es\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-fundacion-comillas-.png\",\"width\":548,\"height\":536,\"caption\":\"Fundaci\u00f3n Comillas\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ciese.comillas\",\"https:\\\/\\\/x.com\\\/CIESEComillas\",\"https:\\\/\\\/www.instagram.com\\\/uniciesecomillas\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-comillas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fundacioncomillas\",\"https:\\\/\\\/twitter.com\\\/FundComillas\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/1533960\\\/admin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/#\\\/schema\\\/person\\\/3cdde58ad1a78de54c94309e39ec81cb\",\"name\":\"fundacion\",\"url\":\"https:\\\/\\\/fundacioncomillas.es\\\/zh-hans\\\/author\\\/fundacion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las lenguas en Espa\u00f1a y sus dialectos - Fundaci\u00f3n Comillas","description":"\u00bfCu\u00e1les son las lenguas oficiales y cu\u00e1les los diferentes dialectos que encontramos dentro de Espa\u00f1a? Te lo aclaramos...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/","og_locale":"zh_CN","og_type":"article","og_title":"Las lenguas en Espa\u00f1a y sus dialectos - Fundaci\u00f3n Comillas","og_description":"\u00bfCu\u00e1les son las lenguas oficiales y cu\u00e1les los diferentes dialectos que encontramos dentro de Espa\u00f1a? Te lo aclaramos...","og_url":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/","og_site_name":"Fundaci\u00f3n Comillas","article_publisher":"https:\/\/www.facebook.com\/ciese.comillas","article_published_time":"2019-11-28T09:17:10+00:00","article_modified_time":"2023-12-04T10:59:34+00:00","og_image":[{"width":599,"height":400,"url":"https:\/\/fundacioncomillas.es\/wp-content\/uploads\/2023\/06\/las-lenguas-en-espana-y-sus-dialectos.jpg","type":"image\/jpeg"}],"author":"fundacion","twitter_card":"summary_large_image","twitter_creator":"@CIESEComillas","twitter_site":"@CIESEComillas","twitter_misc":{"\u4f5c\u8005":"fundacion","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"3 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/#article","isPartOf":{"@id":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/"},"author":{"name":"fundacion","@id":"https:\/\/fundacioncomillas.es\/zh-hans\/#\/schema\/person\/3cdde58ad1a78de54c94309e39ec81cb"},"headline":"Las lenguas en Espa\u00f1a y sus dialectos","datePublished":"2019-11-28T09:17:10+00:00","dateModified":"2023-12-04T10:59:34+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/"},"wordCount":535,"publisher":{"@id":"https:\/\/fundacioncomillas.es\/zh-hans\/#organization"},"image":{"@id":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/#primaryimage"},"thumbnailUrl":"https:\/\/fundacioncomillas.es\/wp-content\/uploads\/2023\/06\/las-lenguas-en-espana-y-sus-dialectos.jpg","keywords":["curiosidades","dialectos","Espa\u00f1ol"],"articleSection":["CULTURA","Curiosidades"],"inLanguage":"zh-Hans"},{"@type":"WebPage","@id":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/","url":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/","name":"Las lenguas en Espa\u00f1a y sus dialectos - Fundaci\u00f3n Comillas","isPartOf":{"@id":"https:\/\/fundacioncomillas.es\/zh-hans\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/#primaryimage"},"image":{"@id":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/#primaryimage"},"thumbnailUrl":"https:\/\/fundacioncomillas.es\/wp-content\/uploads\/2023\/06\/las-lenguas-en-espana-y-sus-dialectos.jpg","datePublished":"2019-11-28T09:17:10+00:00","dateModified":"2023-12-04T10:59:34+00:00","description":"\u00bfCu\u00e1les son las lenguas oficiales y cu\u00e1les los diferentes dialectos que encontramos dentro de Espa\u00f1a? Te lo aclaramos...","breadcrumb":{"@id":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/#primaryimage","url":"https:\/\/fundacioncomillas.es\/wp-content\/uploads\/2023\/06\/las-lenguas-en-espana-y-sus-dialectos.jpg","contentUrl":"https:\/\/fundacioncomillas.es\/wp-content\/uploads\/2023\/06\/las-lenguas-en-espana-y-sus-dialectos.jpg","width":599,"height":400,"caption":"Las lenguas en Espa\u00f1a y sus dialectos"},{"@type":"BreadcrumbList","@id":"https:\/\/fundacioncomillas.es\/zh-hans\/2019\/11\/28\/las-lenguas-en-espana-y-sus-dialectos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacioncomillas.es\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"Las lenguas en Espa\u00f1a y sus dialectos"}]},{"@type":"WebSite","@id":"https:\/\/fundacioncomillas.es\/zh-hans\/#website","url":"https:\/\/fundacioncomillas.es\/zh-hans\/","name":"Fundaci\u00f3n Comillas","description":"La Fundaci\u00f3n Comillas del Espa\u00f1ol y la Cultura Hisp\u00e1nica","publisher":{"@id":"https:\/\/fundacioncomillas.es\/zh-hans\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacioncomillas.es\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/fundacioncomillas.es\/zh-hans\/#organization","name":"Fundaci\u00f3n Comillas","alternateName":"Fundaci\u00f3n Comillas - CIESE","url":"https:\/\/fundacioncomillas.es\/zh-hans\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/fundacioncomillas.es\/zh-hans\/#\/schema\/logo\/image\/","url":"https:\/\/fundacioncomillas.es\/wp-content\/uploads\/2023\/04\/logo-fundacion-comillas-.png","contentUrl":"https:\/\/fundacioncomillas.es\/wp-content\/uploads\/2023\/04\/logo-fundacion-comillas-.png","width":548,"height":536,"caption":"Fundaci\u00f3n Comillas"},"image":{"@id":"https:\/\/fundacioncomillas.es\/zh-hans\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ciese.comillas","https:\/\/x.com\/CIESEComillas","https:\/\/www.instagram.com\/uniciesecomillas\/","https:\/\/www.linkedin.com\/company\/fundacion-comillas\/","https:\/\/www.youtube.com\/user\/fundacioncomillas","https:\/\/twitter.com\/FundComillas","https:\/\/www.linkedin.com\/company\/1533960\/admin\/"]},{"@type":"Person","@id":"https:\/\/fundacioncomillas.es\/zh-hans\/#\/schema\/person\/3cdde58ad1a78de54c94309e39ec81cb","name":"fundacion","url":"https:\/\/fundacioncomillas.es\/zh-hans\/author\/fundacion\/"}]}},"_links":{"self":[{"href":"https:\/\/fundacioncomillas.es\/zh-hans\/wp-json\/wp\/v2\/posts\/8506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacioncomillas.es\/zh-hans\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacioncomillas.es\/zh-hans\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacioncomillas.es\/zh-hans\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacioncomillas.es\/zh-hans\/wp-json\/wp\/v2\/comments?post=8506"}],"version-history":[{"count":3,"href":"https:\/\/fundacioncomillas.es\/zh-hans\/wp-json\/wp\/v2\/posts\/8506\/revisions"}],"predecessor-version":[{"id":10409,"href":"https:\/\/fundacioncomillas.es\/zh-hans\/wp-json\/wp\/v2\/posts\/8506\/revisions\/10409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacioncomillas.es\/zh-hans\/wp-json\/wp\/v2\/media\/8507"}],"wp:attachment":[{"href":"https:\/\/fundacioncomillas.es\/zh-hans\/wp-json\/wp\/v2\/media?parent=8506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacioncomillas.es\/zh-hans\/wp-json\/wp\/v2\/categories?post=8506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacioncomillas.es\/zh-hans\/wp-json\/wp\/v2\/tags?post=8506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}